{"id":10327,"date":"2016-04-20T14:00:41","date_gmt":"2016-04-20T12:00:41","guid":{"rendered":"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/?p=10327"},"modified":"2016-04-16T11:48:47","modified_gmt":"2016-04-16T09:48:47","slug":"reunion-reseau-eod-bern-28042016","status":"publish","type":"post","link":"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/index.php\/reunion-reseau-eod-bern-28042016\/","title":{"rendered":"R\u00e9union du r\u00e9seau EOD \u00e0 Bern (28-29\/4)"},"content":{"rendered":"<h2><em>Le r\u00e9seau EBooks-on-demand (EOD) r\u00e9fl\u00e9chit \u00e0 ses prochains champs d\u2019activit\u00e9<\/em><\/h2>\n<p>Les <strong>28 et 29 avril 2016<\/strong>, <a href=\"https:\/\/books2ebooks.eu\/fr\" target=\"_blank\">EOD<\/a>, r\u00e9seau de 37 biblioth\u00e8ques \u00e0 travers l\u2019Europe, se r\u00e9unit \u00e0 la Biblioth\u00e8que nationale suisse \u00e0 <strong>Bern<\/strong>.<\/p>\n<p>Cette r\u00e9union annuelle sera <strong>prospective<\/strong>. Le service de num\u00e9risation EOD \u00e9volue en fonction des besoins de ses utilisateurs, et de la demande croissante de documentation en ligne. Les partenaires partageront leurs exp\u00e9riences et r\u00e9fl\u00e9chiront \u00e0 la <strong>num\u00e9risation<\/strong> d\u2019ouvrages \u00e9puis\u00e9s, \u00e0 l\u2019<strong>int\u00e9gration<\/strong> d\u2019EOD \u00e0 d\u2019autres syst\u00e8mes et \u00e0 d\u2019autres services, ainsi qu\u2019\u00e0 la <strong>pr\u00e9servation<\/strong> \u00e0 long terme des donn\u00e9es.<\/p>\n<figure id=\"attachment_10328\" aria-describedby=\"caption-attachment-10328\" style=\"width: 515px\" class=\"wp-caption aligncenter\"><a title=\"\" href=\"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/wp-content\/uploads\/Swiss_NL.jpg\" rel=\"attachment wp-att-10328\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10328 size-full\" title=\"\" src=\"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/wp-content\/uploads\/Swiss_NL.jpg\" alt=\"Swiss_NL\" width=\"515\" height=\"194\" srcset=\"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/wp-content\/uploads\/Swiss_NL.jpg 515w, https:\/\/numerabilis.u-paris.fr\/medica\/blog\/wp-content\/uploads\/Swiss_NL-300x113.jpg 300w\" sizes=\"(max-width: 515px) 85vw, 515px\" \/><\/a><figcaption id=\"caption-attachment-10328\" class=\"wp-caption-text\">Photo Clio Turbata<\/figcaption><\/figure>\n<p>Le coordinateur du r\u00e9seau EOD, la <strong>Biblioth\u00e8que r\u00e9gionale et universitaire du Tyrol<\/strong> (<em>universit\u00e9 d\u2019Innsbruck<\/em>) donnera des nouvelles du service et du r\u00e9seau, ainsi que des d\u00e9veloppements du syst\u00e8me informatique et du service d\u2019impression \u00e0 la demande. Un <strong>atelier<\/strong>, en collaboration avec la Biblioth\u00e8que nationale d\u2019Estonie, portera sur la <strong>communication<\/strong> d\u2019EOD.<\/p>\n<p>La r\u00e9union est organis\u00e9e par la Biblioth\u00e8que r\u00e9gionale et universitaire du Tyrol et elle est accueillie par la Biblioth\u00e8que nationale suisse.<\/p>\n<p>Le service EOD a \u00e9t\u00e9 lanc\u00e9 par 13 biblioth\u00e8ques de 8 pays europ\u00e9ens en 2006. Le r\u00e9seau est ouvert \u00e0 des institutions qui souhaitent <strong>num\u00e9riser<\/strong> et rendre accessibles \u00e0 la demande des ouvrages du <strong>domaine public<\/strong>.<\/p>\n<h2>En savoir plus<\/h2>\n<p><a href=\"&#109;&#x61;&#105;&#x6c;&#116;&#x6f;:&#x56;e&#114;&#x6f;&#110;&#x69;&#107;&#x61;&#46;&#x47;r&#117;&#x65;&#110;&#x64;&#104;&#x61;&#109;&#x6d;e&#x72;&#64;&#117;&#x69;&#98;&#x6b;&#46;&#x61;c&#x2e;a&#116;\" target=\"_blank\"><strong>Veronika Gr\u00fcndhammer<\/strong><\/a>, universit\u00e9 d\u2019Innsbruck, biblioth\u00e8que, +43 512 507 8451.<\/p>\n<p>Billet produit par <a href=\"&#109;&#x61;i&#108;&#x74;&#111;&#x3a;o&#110;&#x6e;e&#x2e;&#x6d;&#101;&#x74;s&#64;&#x6e;l&#x69;&#x62;&#46;&#x65;e\" target=\"_blank\">\u00d5nne Mets<\/a>, Biblioth\u00e8que nationale d\u2019Estonie\u00a0 ; trad. fran\u00e7aise\u00a0: <a href=\"mai&#108;&#116;&#111;&#x3a;&#x6a;&#x65;&#x61;&#x6e;&#x2d;fra&#110;&#99;&#111;&#105;&#x73;&#x2e;&#x76;&#x69;&#x6e;&#x63;ent&#64;&#98;&#105;&#x75;&#x73;&#x61;&#x6e;&#x74;&#x65;&#46;pa&#114;&#105;&#115;&#100;&#x65;&#x73;&#x63;&#x61;&#x72;&#x74;es&#46;&#102;&#114;\" target=\"_blank\">J.-F. Vincent<\/a>, Biblioth\u00e8que interuniversitaire de sant\u00e9, Paris<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00e9seau EBooks-on-demand (EOD) r\u00e9fl\u00e9chit \u00e0 ses prochains champs d\u2019activit\u00e9 Les 28 et 29 avril 2016, EOD, r\u00e9seau de 37 biblioth\u00e8ques \u00e0 travers l\u2019Europe, se r\u00e9unit \u00e0 la Biblioth\u00e8que nationale suisse \u00e0 Bern. Cette r\u00e9union annuelle sera prospective. Le service de num\u00e9risation EOD \u00e9volue en fonction des besoins de ses utilisateurs, et de la demande &hellip; <a href=\"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/index.php\/reunion-reseau-eod-bern-28042016\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;R\u00e9union du r\u00e9seau EOD \u00e0 Bern (28-29\/4)&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[360,25,155,191],"class_list":["post-10327","post","type-post","status-publish","format-standard","hentry","category-histoiresante","tag-ebooks","tag-eod","tag-numerisation","tag-partenariat"],"_links":{"self":[{"href":"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10327"}],"collection":[{"href":"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=10327"}],"version-history":[{"count":5,"href":"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10327\/revisions"}],"predecessor-version":[{"id":10334,"href":"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10327\/revisions\/10334"}],"wp:attachment":[{"href":"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=10327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=10327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/numerabilis.u-paris.fr\/medica\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=10327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}